{"id":1693,"count":2,"description":"","link":"https:\/\/shineiberia.tv\/en\/category\/generaciones-en\/","name":"Generaciones","slug":"generaciones-en","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Generaciones archivos - Shine Iberia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.shineiberia.tv\/en\/category\/generaciones-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Generaciones archivos - Shine Iberia\" \/>\n<meta property=\"og:site_name\" content=\"Shine Iberia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.shineiberia.tv\/en\/category\/generaciones-en\/\",\"url\":\"https:\/\/www.shineiberia.tv\/en\/category\/generaciones-en\/\",\"name\":\"Generaciones archivos - Shine Iberia\",\"isPartOf\":{\"@id\":\"https:\/\/shineiberia.tv\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.shineiberia.tv\/en\/category\/generaciones-en\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.shineiberia.tv\/en\/category\/generaciones-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/shineiberia.tv\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Generaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/shineiberia.tv\/en\/#website\",\"url\":\"https:\/\/shineiberia.tv\/en\/\",\"name\":\"Shine Iberia\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/shineiberia.tv\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Generaciones archivos - Shine Iberia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.shineiberia.tv\/en\/category\/generaciones-en\/","og_locale":"en_US","og_type":"article","og_title":"Generaciones archivos - Shine Iberia","og_site_name":"Shine Iberia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.shineiberia.tv\/en\/category\/generaciones-en\/","url":"https:\/\/www.shineiberia.tv\/en\/category\/generaciones-en\/","name":"Generaciones archivos - Shine Iberia","isPartOf":{"@id":"https:\/\/shineiberia.tv\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.shineiberia.tv\/en\/category\/generaciones-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.shineiberia.tv\/en\/category\/generaciones-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/shineiberia.tv\/en\/"},{"@type":"ListItem","position":2,"name":"Generaciones"}]},{"@type":"WebSite","@id":"https:\/\/shineiberia.tv\/en\/#website","url":"https:\/\/shineiberia.tv\/en\/","name":"Shine Iberia","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shineiberia.tv\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/shineiberia.tv\/en\/wp-json\/wp\/v2\/categories\/1693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shineiberia.tv\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/shineiberia.tv\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/shineiberia.tv\/en\/wp-json\/wp\/v2\/posts?categories=1693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}